{"id":8800,"date":"2026-04-03T16:52:56","date_gmt":"2026-04-03T14:52:56","guid":{"rendered":"https:\/\/academiespatiale.fr\/?post_type=tribe_events&#038;p=8800"},"modified":"2026-04-03T16:52:57","modified_gmt":"2026-04-03T14:52:57","slug":"inscription-inauguration-de-lantenne-bande-s-observatoire-du-sirta","status":"publish","type":"tribe_events","link":"https:\/\/academiespatiale.fr\/index.php\/event\/inscription-inauguration-de-lantenne-bande-s-observatoire-du-sirta\/","title":{"rendered":"[Inscription] Inauguration de l\u2019antenne Bande S \u2013 Observatoire du SIRTA"},"content":{"rendered":"<div  class=\"tribe-events-schedule tribe-clearfix\" >\n\t<p class=\"tribe-events-schedule__datetime\">\n\t\t<span class=\"tribe-events-schedule__date tribe-events-schedule__date--start\">\n\t\t\t15 avril\t\t<\/span>\n\n\t\t\t\t\t<span class=\"tribe-events-schedule__separator tribe-events-schedule__separator--date\">\n\t\t\t\t : \t\t\t<\/span>\n\t\t\t<span class=\"tribe-events-schedule__time tribe-events-schedule__time--start\">\n\t\t\t\t16h00\t\t\t<\/span>\n\t\t\n\t\t\t\t\t\t\t\t\t<span class=\"tribe-events-schedule__separator tribe-events-schedule__separator--time\">\n\t\t\t\t\t&#8211;\t\t\t\t<\/span>\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"tribe-events-schedule__time tribe-events-schedule__time--end\">\n\t\t\t\t\t18h00\t\t\t\t<\/span>\n\t\t\t\n\t\t\t\t\t\t<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-cover is-light\" style=\"padding-top:var(--wp--preset--spacing--80);padding-right:var(--wp--preset--spacing--80);padding-bottom:var(--wp--preset--spacing--80);padding-left:var(--wp--preset--spacing--80)\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-white-background-color has-background-dim-100 has-background-dim\"><\/span><div class=\"wp-block-cover__inner-container is-layout-constrained wp-container-core-cover-is-layout-3ae6a1a4 wp-block-cover-is-layout-constrained\">\n<div class=\"wp-block-columns has-text-color has-link-color wp-elements-1 is-layout-flex wp-container-core-columns-is-layout-e09de6c1 wp-block-columns-is-layout-flex\" style=\"color:#b1b1b1;margin-top:-25px;margin-bottom:20px;padding-top:0;padding-right:0;padding-bottom:0;padding-left:0;font-size:15px\">\n<div class=\"wp-block-column has-text-color has-link-color wp-elements-2 is-layout-flow wp-block-column-is-layout-flow\" style=\"color:#a1a1a1;padding-top:0;padding-bottom:0;font-size:15px;font-style:normal;font-weight:100;flex-basis:100%\"><div class=\"wp-block-aioseo-breadcrumbs\"><div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/academiespatiale.fr\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/academiespatiale.fr\/index.php\/events\/\" title=\"\u00c9v\u00e8nements\">\u00c9v\u00e8nements<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t[Inscription] Inauguration de l\u2019antenne Bande S \u2013 Observatoire du SIRTA\n\t\t<\/span><\/div><\/div><\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mercredi 15 avril 2026, \u00e0 partir de 15h45, rendez-vous \u00e0 l&rsquo;Observatoire du SIRTA pour l&rsquo;inauguration de l&rsquo;antenne Bande S SYLVIE financ\u00e9e par l&rsquo;Acad\u00e9mie Spatiale d&rsquo;\u00cele-de-France. <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cette nouvelle antenne, install\u00e9e \u00e0 proximit\u00e9 du campus de l\u2019\u00c9cole polytechnique, servira \u00e0 assurer des communications haut d\u00e9bit avec le satellite IonSat du Centre spatial de l\u2019\u00c9cole polytechnique, dont le lancement est pr\u00e9vu en 2027.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-text-align-center wp-block-paragraph\"><strong>Inauguration de l&rsquo;antenne Bande S Sylvie<br><\/strong><br><strong>Mercredi 15 avril 2026<br><\/strong>de 15h45 \u00e0 18h<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"font-size:15px\">Observatoire SIRTA<br>\u00c9cole Polytechnique<br>Bd des Mar\u00e9chaux B\u00e2t 87 &amp; 88, 91120 Palaiseau<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Gratuit, sur inscription<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/evento.renater.fr\/survey\/inauguration-de-l-antenne-bande-s_-observatoire-du-sirta-j7zy0g6t\" target=\"_blank\" rel=\" noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"734\" height=\"1024\" src=\"https:\/\/academiespatiale.fr\/wp-content\/uploads\/2026\/04\/Inauguration-antenne-bande-S_avril2026-734x1024.png\" alt=\"\" class=\"wp-image-8789\" srcset=\"https:\/\/academiespatiale.fr\/wp-content\/uploads\/2026\/04\/Inauguration-antenne-bande-S_avril2026-734x1024.png 734w, https:\/\/academiespatiale.fr\/wp-content\/uploads\/2026\/04\/Inauguration-antenne-bande-S_avril2026-215x300.png 215w, https:\/\/academiespatiale.fr\/wp-content\/uploads\/2026\/04\/Inauguration-antenne-bande-S_avril2026-768x1072.png 768w, https:\/\/academiespatiale.fr\/wp-content\/uploads\/2026\/04\/Inauguration-antenne-bande-S_avril2026.png 847w\" sizes=\"auto, (max-width: 734px) 100vw, 734px\" \/><\/a><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"border-width:1px;padding-top:var(--wp--preset--spacing--60);padding-right:var(--wp--preset--spacing--60);padding-bottom:var(--wp--preset--spacing--60);padding-left:var(--wp--preset--spacing--60)\"><strong>INSCRIPTION<br><\/strong>Nous vous remercions de bien vouloir confirmer votre participation avant le vendredi 10 avril<br>\u00c9v\u00e8nement limit\u00e9 \u00e0 100 personnes<br>&gt;&gt;&gt; <a href=\"https:\/\/evento.renater.fr\/survey\/inauguration-de-l-antenne-bande-s_-observatoire-du-sirta-j7zy0g6t\" target=\"_blank\" rel=\"noopener\" title=\"\">Formulaire de pr\u00e9sence<\/a> &lt;&lt;&lt;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">PROGRAMME<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>15h45<\/strong> \u2192 Accueil<\/li>\n\n\n\n<li><strong>16h00<\/strong> \u2192 Introduction par <strong>Pascal Chabert<\/strong><\/li>\n\n\n\n<li><strong>16h10<\/strong> \u2192 Pr\u00e9sentation du Centre Spatial de l&rsquo;\u00c9cole polytechnique par <strong>Nicolas Lequette<\/strong><\/li>\n\n\n\n<li><strong>16h20<\/strong> \u2192 Pr\u00e9sentation de l&rsquo;Acad\u00e9mie Spatiale d&rsquo;\u00cele-de-France par <strong>Philippe Keckhut<\/strong><\/li>\n\n\n\n<li><strong>16h30<\/strong> \u2192 Visite de l&rsquo;Antenne Bande S Sylvie<\/li>\n\n\n\n<li><strong>16h40<\/strong> \u2192 D\u00e9monstration de la station sol par <strong>Tony Colin<\/strong><\/li>\n\n\n\n<li><strong>17h00<\/strong> \u2192 Cocktail<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Le Centre Spatial \u00c9tudiant de l\u2019\u00c9cole polytechnique (CSEP) a r\u00e9cemment install\u00e9 une nouvelle antenne bande S, baptis\u00e9e Sylvie (System Link for&nbsp;VLEO Information Exchange), sur le site du SIRTA, \u00e0 proximit\u00e9 du campus de l\u2019\u00c9cole polytechnique.&nbsp;La bande S (2-4 GHz) est utilis\u00e9e pour les communications par satellite, les radars, ou encore la surveillance m\u00e9t\u00e9orologique.<br><br>Fournie par la soci\u00e9t\u00e9 Adrelys_qui \u00e9quipe \u00e9galement le laboratoire LATMOS_cette antenne permettra la r\u00e9ception des signaux \u00e9mis par tous&nbsp;types d\u2019objets en orbite autour de la Terre, notamment par le CubeSat IonSat, actuellement en d\u00e9veloppement par les \u00e9tudiants et ing\u00e9nieur du&nbsp;CSEP.<br><br>Cette installation vient compl\u00e9ter la station sol existante du CSEP, d\u00e9j\u00e0 \u00e9quip\u00e9e d\u2019une antenne UHF\/VHF (Ultra High Frequency \/ Very High&nbsp;Frequency). Les bandes UHF et VHF sont principalement utilis\u00e9es pour les communications \u00e0 bas d\u00e9bit, comme l\u2019envoi de commandes et la r\u00e9ception&nbsp;de t\u00e9l\u00e9m\u00e9tries, tandis que la bande S permet de recevoir des volumes de donn\u00e9es plus importants, tels que des mesures scientifiques ou des&nbsp;images. Cette \u00e9volution renforce la capacit\u00e9 op\u00e9rationnelle du CSEP pour ses missions spatiales.<br><br><strong>L\u2019antenne Sylvie s\u2019inscrit dans le cadre du programme national Acad\u00e9mie Spatiale France 2030, qui vise \u00e0 soutenir la formation et l\u2019innovation&nbsp;dans le domaine spatial.<\/strong> Elle sera utilis\u00e9e non seulement pour les missions r\u00e9elles du CSEP, mais aussi \u00e0 des fins \u00e9ducatives, notamment lors de travaux pratiques, d\u00e9monstrations et projets \u00e9tudiants autour des communications satellitaires et du traitement de donn\u00e9es en orbite.<\/p>\n\n\n\n<p class=\"has-text-align-left has-background-color-background-color has-background wp-block-paragraph\">Plus d&rsquo;infos <br>\u2192 <a href=\"https:\/\/sirta.ipsl.fr\/fr\/home-fr-2\/\">SIRTA \u2013 Atmospheric Observatory<\/a><br>\u2192 <a href=\"https:\/\/portail.polytechnique.edu\/esds\/actualites\/antenne-bande-s-operationnelle\">Antenne Bande S op\u00e9rationnelle &#8211; M\u00e9c\u00e9nat Espace, science et d\u00e9fis du spatial<\/a><br>\u2192 <a href=\"https:\/\/portail.polytechnique.edu\/esds\/actualites\/installation-dune-antenne-bande-s\">Installation d&rsquo;une Antenne Bande S &#8211; M\u00e9c\u00e9nat Espace, science et d\u00e9fis du spatial<\/a><br>\u2192 <a href=\"https:\/\/www.polytechnique.edu\/recherche\/chaires\/les-chaires-de-transports-mobilites-et-espace\/mecenat-denseignement-espace-science-et-defis-du-spatial\/centre-spatial-de-lecole-polytechnique\">Centre Spatial de l&rsquo;\u00c9cole Polytechnique &#8211; \u00c9cole polytechnique, \u00e9cole d&rsquo;ing\u00e9nieur<\/a><\/p>\n<\/div><\/div>\n\n\n\t<div  class=\"tribe-block tribe-block__events-link\" >\n\t\t<div class=\"tribe-events tribe-common\">\n\t\t\t<div class=\"tribe-events-c-subscribe-dropdown__container\">\n\t\t\t\t<div class=\"tribe-events-c-subscribe-dropdown\">\n\t\t\t\t\t<div class=\"tribe-common-c-btn-border tribe-events-c-subscribe-dropdown__button\">\n\t\t\t\t\t\t<svg\n\t class=\"tribe-common-c-svgicon tribe-common-c-svgicon--cal-export tribe-events-c-subscribe-dropdown__export-icon\" \taria-hidden=\"true\"\n\tviewBox=\"0 0 23 17\"\n\txmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n>\n\t<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M.128.896V16.13c0 .211.145.383.323.383h15.354c.179 0 .323-.172.323-.383V.896c0-.212-.144-.383-.323-.383H.451C.273.513.128.684.128.896Zm16 6.742h-.901V4.679H1.009v10.729h14.218v-3.336h.901V7.638ZM1.01 1.614h14.218v2.058H1.009V1.614Z\" \/>\n\t<path d=\"M20.5 9.846H8.312M18.524 6.953l2.89 2.909-2.855 2.855\" stroke-width=\"1.2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n<\/svg>\n\t\t\t\t\t\t<button\n\t\t\t\t\t\t\tclass=\"tribe-events-c-subscribe-dropdown__button-text\"\n\t\t\t\t\t\t\taria-expanded=\"false\"\n\t\t\t\t\t\t\taria-controls=\"tribe-events-subscribe-dropdown-content\"\n\t\t\t\t\t\t\taria-label=\"Afficher les liens permettant d\u2019ajouter des \u00e9v\u00e8nements \u00e0 votre calendrier\"\n\t\t\t\t\t\t>\n\t\t\t\t\t\t\tAjouter au calendrier\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t<svg\n\t class=\"tribe-common-c-svgicon tribe-common-c-svgicon--caret-down tribe-events-c-subscribe-dropdown__button-icon\" \taria-hidden=\"true\"\n\tviewBox=\"0 0 10 7\"\n\txmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n>\n\t<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M1.008.609L5 4.6 8.992.61l.958.958L5 6.517.05 1.566l.958-.958z\" class=\"tribe-common-c-svgicon__svg-fill\"\/>\n<\/svg>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"tribe-events-subscribe-dropdown-content\" class=\"tribe-events-c-subscribe-dropdown__content\">\n\t\t\t\t\t\t<ul class=\"tribe-events-c-subscribe-dropdown__list\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"tribe-events-c-subscribe-dropdown__list-item tribe-events-c-subscribe-dropdown__list-item--gcal\">\n\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\t\t\t\t\thref=\"https:\/\/www.google.com\/calendar\/event?action=TEMPLATE&#038;dates=20260415T160000\/20260415T180000&#038;text=%5BInscription%5D%20Inauguration%20de%20l%E2%80%99antenne%20Bande%20S%20%E2%80%93%20Observatoire%20du%20SIRTA&#038;details=%3Cdiv+class%3D%22wp-block-cover+is-light%22+style%3D%22padding-top%3Avar%28--wp--preset--spacing--80%29%3Bpadding-right%3Avar%28--wp--preset--spacing--80%29%3Bpadding-bottom%3Avar%28--wp--preset--spacing--80%29%3Bpadding-left%3Avar%28--wp--preset--spacing--80%29%22%3E%3Cspan+aria-hidden%3D%22true%22+class%3D%22wp-block-cover__background+has-white-background-color+has-background-dim-100+has-background-dim%22%3E%3C%2Fspan%3E%3Cdiv+class%3D%22wp-block-cover__inner-container%22%3E%3Cp%3E%3Cstrong%3EMercredi+15+avril+2026%2C+%C3%A0+partir+de+15h45%2C+rendez-vous+%C3%A0+l%27Observatoire+du+SIRTA+pour+l%27inauguration+de+l%27antenne+Bande+S+SYLVIE+financ%C3%A9e+par+l%27Acad%C3%A9mie+Spatiale+d%27%C3%8Ele-de-France.+%3C%2Fstrong%3E%3C%2Fp%3E+%3Cp%3ECette+nouvelle+antenne%2C+install%C3%A9e+%C3%A0+proximit%C3%A9+du+campus+de+l%E2%80%99%C3%89cole+polytechnique%2C+servira+%C3%A0+assurer+des+communications+haut+d%C3%A9bit+avec+le+satellite+IonSat+du+Centre+spatial+de+l%E2%80%99%C3%89cole+polytechnique%2C+dont+le+lancement+est+pr%C3%A9vu+en+2027.%3C%2Fp%3E+%3Cdiv+class%3D%22wp-block-columns%22%3E%3Cdiv+class%3D%22wp-block-column+is-vertically-aligned-center%22%3E%3Cp+class%3D%22has-text-align%3C%2Fdiv%3E%3C%2Fdiv%3E%3C%2Fdiv%3E%3C%2Fdiv%3E%28Voir+toute+la+description+de+%C3%A9v%C3%A8nement+ici%C2%A0%3A+https%3A%2F%2Facademiespatiale.fr%2Findex.php%2Fevent%2Finscription-inauguration-de-lantenne-bande-s-observatoire-du-sirta%2F%29&#038;trp=false&#038;ctz=Europe\/Paris&#038;sprop=website:https:\/\/academiespatiale.fr\"\n\t\t\t\t\t\t\t\t\t\tclass=\"tribe-events-c-subscribe-dropdown__list-item-link\"\n\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\"\n\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer nofollow noindex\"\n\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\tGoogle Agenda\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"tribe-events-c-subscribe-dropdown__list-item tribe-events-c-subscribe-dropdown__list-item--ical\">\n\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\t\t\t\t\thref=\"\"\n\t\t\t\t\t\t\t\t\t\tclass=\"tribe-events-c-subscribe-dropdown__list-item-link\"\n\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\"\n\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer nofollow noindex\"\n\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\tiCalendar\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"tribe-events-c-subscribe-dropdown__list-item tribe-events-c-subscribe-dropdown__list-item--outlook-365\">\n\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\t\t\t\t\thref=\"\"\n\t\t\t\t\t\t\t\t\t\tclass=\"tribe-events-c-subscribe-dropdown__list-item-link\"\n\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\"\n\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer nofollow noindex\"\n\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\tOutlook 365\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"tribe-events-c-subscribe-dropdown__list-item tribe-events-c-subscribe-dropdown__list-item--outlook-live\">\n\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\t\t\t\t\thref=\"\"\n\t\t\t\t\t\t\t\t\t\tclass=\"tribe-events-c-subscribe-dropdown__list-item-link\"\n\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\"\n\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer nofollow noindex\"\n\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\tOutlook Live\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":8790,"template":"","meta":{"_monsterinsights_skip_tracking":false,"_EventAllDay":false,"_EventTimezone":"Europe\/Paris","_EventStartDate":"2026-04-15 16:00:00","_EventEndDate":"2026-04-15 18:00:00","_EventStartDateUTC":"2026-04-15 14:00:00","_EventEndDateUTC":"2026-04-15 16:00:00","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"\u20ac","_EventCurrencyCode":"EUR","_EventCurrencyPosition":"suffix","_EventDateTimeSeparator":" : ","_EventTimeRangeSeparator":"-","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-8800","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Mercredi 15 avril 2026, \u00e0 partir de 15h45, rendez-vous \u00e0 l&#039;Observatoire du SIRTA pour l&#039;inauguration de l&#039;antenne Bande S SYLVIE financ\u00e9e par l&#039;Acad\u00e9mie Spatiale d&#039;\u00cele-de-France. Cette nouvelle antenne, install\u00e9e \u00e0 proximit\u00e9 du campus de l\u2019\u00c9cole polytechnique, servira \u00e0 assurer des communications haut d\u00e9bit avec le satellite IonSat du Centre spatial de l\u2019\u00c9cole polytechnique, dont le\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Acad\u00e9mie Spatiale\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/academiespatiale.fr\/index.php\/event\/inscription-inauguration-de-lantenne-bande-s-observatoire-du-sirta\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Acad\u00e9mie Spatiale d&#039;\u00cele-de-France - Ensemble pour un nouvel espace durable pour tous et toutes\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"[Inscription] Inauguration de l\u2019antenne Bande S \u2013 Observatoire du SIRTA - Acad\u00e9mie Spatiale d&#039;\u00cele-de-France\" \/>\n\t\t<meta property=\"og:description\" content=\"Mercredi 15 avril 2026, \u00e0 partir de 15h45, rendez-vous \u00e0 l&#039;Observatoire du SIRTA pour l&#039;inauguration de l&#039;antenne Bande S SYLVIE financ\u00e9e par l&#039;Acad\u00e9mie Spatiale d&#039;\u00cele-de-France. Cette nouvelle antenne, install\u00e9e \u00e0 proximit\u00e9 du campus de l\u2019\u00c9cole polytechnique, servira \u00e0 assurer des communications haut d\u00e9bit avec le satellite IonSat du Centre spatial de l\u2019\u00c9cole polytechnique, dont le\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/academiespatiale.fr\/index.php\/event\/inscription-inauguration-de-lantenne-bande-s-observatoire-du-sirta\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/academiespatiale.fr\/wp-content\/uploads\/2026\/04\/Inauguration_bandeS_sirta_palaiseau_avril2026.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/academiespatiale.fr\/wp-content\/uploads\/2026\/04\/Inauguration_bandeS_sirta_palaiseau_avril2026.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-04-03T14:52:56+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-04-03T14:52:57+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Acadmie-Spatiale-dle-de-France\/61560696669781\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@Ac_Spatiale\" \/>\n\t\t<meta name=\"twitter:title\" content=\"[Inscription] Inauguration de l\u2019antenne Bande S \u2013 Observatoire du SIRTA - Acad\u00e9mie Spatiale d&#039;\u00cele-de-France\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Mercredi 15 avril 2026, \u00e0 partir de 15h45, rendez-vous \u00e0 l&#039;Observatoire du SIRTA pour l&#039;inauguration de l&#039;antenne Bande S SYLVIE financ\u00e9e par l&#039;Acad\u00e9mie Spatiale d&#039;\u00cele-de-France. Cette nouvelle antenne, install\u00e9e \u00e0 proximit\u00e9 du campus de l\u2019\u00c9cole polytechnique, servira \u00e0 assurer des communications haut d\u00e9bit avec le satellite IonSat du Centre spatial de l\u2019\u00c9cole polytechnique, dont le\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@Ac_Spatiale\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/academiespatiale.fr\/wp-content\/uploads\/2026\/04\/Inauguration_bandeS_sirta_palaiseau_avril2026.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/academiespatiale.fr\\\/index.php\\\/event\\\/inscription-inauguration-de-lantenne-bande-s-observatoire-du-sirta\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/academiespatiale.fr#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/academiespatiale.fr\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/academiespatiale.fr\\\/index.php\\\/events\\\/#listItem\",\"name\":\"\\u00c9v\\u00e8nements\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/academiespatiale.fr\\\/index.php\\\/events\\\/#listItem\",\"position\":2,\"name\":\"\\u00c9v\\u00e8nements\",\"item\":\"https:\\\/\\\/academiespatiale.fr\\\/index.php\\\/events\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/academiespatiale.fr\\\/index.php\\\/event\\\/inscription-inauguration-de-lantenne-bande-s-observatoire-du-sirta\\\/#listItem\",\"name\":\"[Inscription] Inauguration de l\\u2019antenne Bande S \\u2013 Observatoire du SIRTA\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/academiespatiale.fr#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/academiespatiale.fr\\\/index.php\\\/event\\\/inscription-inauguration-de-lantenne-bande-s-observatoire-du-sirta\\\/#listItem\",\"position\":3,\"name\":\"[Inscription] Inauguration de l\\u2019antenne Bande S \\u2013 Observatoire du SIRTA\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/academiespatiale.fr\\\/index.php\\\/events\\\/#listItem\",\"name\":\"\\u00c9v\\u00e8nements\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/academiespatiale.fr\\\/#organization\",\"name\":\"academiespatiale.fr\",\"description\":\"Ensemble pour un nouvel espace durable pour tous et toutes\",\"url\":\"https:\\\/\\\/academiespatiale.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/academiespatiale.fr\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/ASIDF-Fr2030_logo_compact_RVB.png\",\"@id\":\"https:\\\/\\\/academiespatiale.fr\\\/index.php\\\/event\\\/inscription-inauguration-de-lantenne-bande-s-observatoire-du-sirta\\\/#organizationLogo\",\"width\":1716,\"height\":473},\"image\":{\"@id\":\"https:\\\/\\\/academiespatiale.fr\\\/index.php\\\/event\\\/inscription-inauguration-de-lantenne-bande-s-observatoire-du-sirta\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Acadmie-Spatiale-dle-de-France\\\/61560696669781\\\/\",\"https:\\\/\\\/x.com\\\/Ac_Spatiale\",\"https:\\\/\\\/www.instagram.com\\\/academie_spatiale\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/academie-spatiale-ile-de-france\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/academiespatiale.fr\\\/index.php\\\/author\\\/academiespatiale-fr\\\/#author\",\"url\":\"https:\\\/\\\/academiespatiale.fr\\\/index.php\\\/author\\\/academiespatiale-fr\\\/\",\"name\":\"Acad\\u00e9mie Spatiale\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/academiespatiale.fr\\\/index.php\\\/event\\\/inscription-inauguration-de-lantenne-bande-s-observatoire-du-sirta\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b8c278e938957e0409fe4c924c42e4584982f9e44f5269988c79fe11689bce58?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Acad\\u00e9mie Spatiale\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/academiespatiale.fr\\\/index.php\\\/event\\\/inscription-inauguration-de-lantenne-bande-s-observatoire-du-sirta\\\/#webpage\",\"url\":\"https:\\\/\\\/academiespatiale.fr\\\/index.php\\\/event\\\/inscription-inauguration-de-lantenne-bande-s-observatoire-du-sirta\\\/\",\"name\":\"[Inscription] Inauguration de l\\u2019antenne Bande S \\u2013 Observatoire du SIRTA - Acad\\u00e9mie Spatiale d'\\u00cele-de-France\",\"description\":\"Mercredi 15 avril 2026, \\u00e0 partir de 15h45, rendez-vous \\u00e0 l'Observatoire du SIRTA pour l'inauguration de l'antenne Bande S SYLVIE financ\\u00e9e par l'Acad\\u00e9mie Spatiale d'\\u00cele-de-France. Cette nouvelle antenne, install\\u00e9e \\u00e0 proximit\\u00e9 du campus de l\\u2019\\u00c9cole polytechnique, servira \\u00e0 assurer des communications haut d\\u00e9bit avec le satellite IonSat du Centre spatial de l\\u2019\\u00c9cole polytechnique, dont le\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/academiespatiale.fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/academiespatiale.fr\\\/index.php\\\/event\\\/inscription-inauguration-de-lantenne-bande-s-observatoire-du-sirta\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/academiespatiale.fr\\\/index.php\\\/author\\\/academiespatiale-fr\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/academiespatiale.fr\\\/index.php\\\/author\\\/academiespatiale-fr\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/academiespatiale.fr\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Inauguration_bandeS_sirta_palaiseau_avril2026.png\",\"@id\":\"https:\\\/\\\/academiespatiale.fr\\\/index.php\\\/event\\\/inscription-inauguration-de-lantenne-bande-s-observatoire-du-sirta\\\/#mainImage\",\"width\":750,\"height\":500},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/academiespatiale.fr\\\/index.php\\\/event\\\/inscription-inauguration-de-lantenne-bande-s-observatoire-du-sirta\\\/#mainImage\"},\"datePublished\":\"2026-04-03T16:52:56+02:00\",\"dateModified\":\"2026-04-03T16:52:57+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/academiespatiale.fr\\\/#website\",\"url\":\"https:\\\/\\\/academiespatiale.fr\\\/\",\"name\":\"academiespatiale.fr\",\"description\":\"Ensemble pour un nouvel espace durable pour tous et toutes\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/academiespatiale.fr\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"[Inscription] Inauguration de l\u2019antenne Bande S \u2013 Observatoire du SIRTA - Acad\u00e9mie Spatiale d'\u00cele-de-France","description":"Mercredi 15 avril 2026, \u00e0 partir de 15h45, rendez-vous \u00e0 l'Observatoire du SIRTA pour l'inauguration de l'antenne Bande S SYLVIE financ\u00e9e par l'Acad\u00e9mie Spatiale d'\u00cele-de-France. Cette nouvelle antenne, install\u00e9e \u00e0 proximit\u00e9 du campus de l\u2019\u00c9cole polytechnique, servira \u00e0 assurer des communications haut d\u00e9bit avec le satellite IonSat du Centre spatial de l\u2019\u00c9cole polytechnique, dont le","canonical_url":"https:\/\/academiespatiale.fr\/index.php\/event\/inscription-inauguration-de-lantenne-bande-s-observatoire-du-sirta\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/academiespatiale.fr\/index.php\/event\/inscription-inauguration-de-lantenne-bande-s-observatoire-du-sirta\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/academiespatiale.fr#listItem","position":1,"name":"Home","item":"https:\/\/academiespatiale.fr","nextItem":{"@type":"ListItem","@id":"https:\/\/academiespatiale.fr\/index.php\/events\/#listItem","name":"\u00c9v\u00e8nements"}},{"@type":"ListItem","@id":"https:\/\/academiespatiale.fr\/index.php\/events\/#listItem","position":2,"name":"\u00c9v\u00e8nements","item":"https:\/\/academiespatiale.fr\/index.php\/events\/","nextItem":{"@type":"ListItem","@id":"https:\/\/academiespatiale.fr\/index.php\/event\/inscription-inauguration-de-lantenne-bande-s-observatoire-du-sirta\/#listItem","name":"[Inscription] Inauguration de l\u2019antenne Bande S \u2013 Observatoire du SIRTA"},"previousItem":{"@type":"ListItem","@id":"https:\/\/academiespatiale.fr#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/academiespatiale.fr\/index.php\/event\/inscription-inauguration-de-lantenne-bande-s-observatoire-du-sirta\/#listItem","position":3,"name":"[Inscription] Inauguration de l\u2019antenne Bande S \u2013 Observatoire du SIRTA","previousItem":{"@type":"ListItem","@id":"https:\/\/academiespatiale.fr\/index.php\/events\/#listItem","name":"\u00c9v\u00e8nements"}}]},{"@type":"Organization","@id":"https:\/\/academiespatiale.fr\/#organization","name":"academiespatiale.fr","description":"Ensemble pour un nouvel espace durable pour tous et toutes","url":"https:\/\/academiespatiale.fr\/","logo":{"@type":"ImageObject","url":"https:\/\/academiespatiale.fr\/wp-content\/uploads\/2026\/03\/ASIDF-Fr2030_logo_compact_RVB.png","@id":"https:\/\/academiespatiale.fr\/index.php\/event\/inscription-inauguration-de-lantenne-bande-s-observatoire-du-sirta\/#organizationLogo","width":1716,"height":473},"image":{"@id":"https:\/\/academiespatiale.fr\/index.php\/event\/inscription-inauguration-de-lantenne-bande-s-observatoire-du-sirta\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/people\/Acadmie-Spatiale-dle-de-France\/61560696669781\/","https:\/\/x.com\/Ac_Spatiale","https:\/\/www.instagram.com\/academie_spatiale\/","https:\/\/www.linkedin.com\/company\/academie-spatiale-ile-de-france\/"]},{"@type":"Person","@id":"https:\/\/academiespatiale.fr\/index.php\/author\/academiespatiale-fr\/#author","url":"https:\/\/academiespatiale.fr\/index.php\/author\/academiespatiale-fr\/","name":"Acad\u00e9mie Spatiale","image":{"@type":"ImageObject","@id":"https:\/\/academiespatiale.fr\/index.php\/event\/inscription-inauguration-de-lantenne-bande-s-observatoire-du-sirta\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/b8c278e938957e0409fe4c924c42e4584982f9e44f5269988c79fe11689bce58?s=96&d=mm&r=g","width":96,"height":96,"caption":"Acad\u00e9mie Spatiale"}},{"@type":"WebPage","@id":"https:\/\/academiespatiale.fr\/index.php\/event\/inscription-inauguration-de-lantenne-bande-s-observatoire-du-sirta\/#webpage","url":"https:\/\/academiespatiale.fr\/index.php\/event\/inscription-inauguration-de-lantenne-bande-s-observatoire-du-sirta\/","name":"[Inscription] Inauguration de l\u2019antenne Bande S \u2013 Observatoire du SIRTA - Acad\u00e9mie Spatiale d'\u00cele-de-France","description":"Mercredi 15 avril 2026, \u00e0 partir de 15h45, rendez-vous \u00e0 l'Observatoire du SIRTA pour l'inauguration de l'antenne Bande S SYLVIE financ\u00e9e par l'Acad\u00e9mie Spatiale d'\u00cele-de-France. Cette nouvelle antenne, install\u00e9e \u00e0 proximit\u00e9 du campus de l\u2019\u00c9cole polytechnique, servira \u00e0 assurer des communications haut d\u00e9bit avec le satellite IonSat du Centre spatial de l\u2019\u00c9cole polytechnique, dont le","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/academiespatiale.fr\/#website"},"breadcrumb":{"@id":"https:\/\/academiespatiale.fr\/index.php\/event\/inscription-inauguration-de-lantenne-bande-s-observatoire-du-sirta\/#breadcrumblist"},"author":{"@id":"https:\/\/academiespatiale.fr\/index.php\/author\/academiespatiale-fr\/#author"},"creator":{"@id":"https:\/\/academiespatiale.fr\/index.php\/author\/academiespatiale-fr\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/academiespatiale.fr\/wp-content\/uploads\/2026\/04\/Inauguration_bandeS_sirta_palaiseau_avril2026.png","@id":"https:\/\/academiespatiale.fr\/index.php\/event\/inscription-inauguration-de-lantenne-bande-s-observatoire-du-sirta\/#mainImage","width":750,"height":500},"primaryImageOfPage":{"@id":"https:\/\/academiespatiale.fr\/index.php\/event\/inscription-inauguration-de-lantenne-bande-s-observatoire-du-sirta\/#mainImage"},"datePublished":"2026-04-03T16:52:56+02:00","dateModified":"2026-04-03T16:52:57+02:00"},{"@type":"WebSite","@id":"https:\/\/academiespatiale.fr\/#website","url":"https:\/\/academiespatiale.fr\/","name":"academiespatiale.fr","description":"Ensemble pour un nouvel espace durable pour tous et toutes","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/academiespatiale.fr\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"Acad\u00e9mie Spatiale d'\u00cele-de-France - Ensemble pour un nouvel espace durable pour tous et toutes","og:type":"article","og:title":"[Inscription] Inauguration de l\u2019antenne Bande S \u2013 Observatoire du SIRTA - Acad\u00e9mie Spatiale d'\u00cele-de-France","og:description":"Mercredi 15 avril 2026, \u00e0 partir de 15h45, rendez-vous \u00e0 l'Observatoire du SIRTA pour l'inauguration de l'antenne Bande S SYLVIE financ\u00e9e par l'Acad\u00e9mie Spatiale d'\u00cele-de-France. Cette nouvelle antenne, install\u00e9e \u00e0 proximit\u00e9 du campus de l\u2019\u00c9cole polytechnique, servira \u00e0 assurer des communications haut d\u00e9bit avec le satellite IonSat du Centre spatial de l\u2019\u00c9cole polytechnique, dont le","og:url":"https:\/\/academiespatiale.fr\/index.php\/event\/inscription-inauguration-de-lantenne-bande-s-observatoire-du-sirta\/","og:image":"https:\/\/academiespatiale.fr\/wp-content\/uploads\/2026\/04\/Inauguration_bandeS_sirta_palaiseau_avril2026.png","og:image:secure_url":"https:\/\/academiespatiale.fr\/wp-content\/uploads\/2026\/04\/Inauguration_bandeS_sirta_palaiseau_avril2026.png","og:image:width":750,"og:image:height":500,"article:published_time":"2026-04-03T14:52:56+00:00","article:modified_time":"2026-04-03T14:52:57+00:00","article:publisher":"https:\/\/www.facebook.com\/people\/Acadmie-Spatiale-dle-de-France\/61560696669781\/","twitter:card":"summary_large_image","twitter:site":"@Ac_Spatiale","twitter:title":"[Inscription] Inauguration de l\u2019antenne Bande S \u2013 Observatoire du SIRTA - Acad\u00e9mie Spatiale d'\u00cele-de-France","twitter:description":"Mercredi 15 avril 2026, \u00e0 partir de 15h45, rendez-vous \u00e0 l'Observatoire du SIRTA pour l'inauguration de l'antenne Bande S SYLVIE financ\u00e9e par l'Acad\u00e9mie Spatiale d'\u00cele-de-France. Cette nouvelle antenne, install\u00e9e \u00e0 proximit\u00e9 du campus de l\u2019\u00c9cole polytechnique, servira \u00e0 assurer des communications haut d\u00e9bit avec le satellite IonSat du Centre spatial de l\u2019\u00c9cole polytechnique, dont le","twitter:creator":"@Ac_Spatiale","twitter:image":"https:\/\/academiespatiale.fr\/wp-content\/uploads\/2026\/04\/Inauguration_bandeS_sirta_palaiseau_avril2026.png"},"aioseo_meta_data":{"post_id":"8800","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2026-04-03 14:52:57","updated":"2026-04-03 14:53:16","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/academiespatiale.fr\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/academiespatiale.fr\/index.php\/events\/\" title=\"\u00c9v\u00e8nements\">\u00c9v\u00e8nements<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t[Inscription] Inauguration de l\u2019antenne Bande S \u2013 Observatoire du SIRTA\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/academiespatiale.fr"},{"label":"\u00c9v\u00e8nements","link":"https:\/\/academiespatiale.fr\/index.php\/events\/"},{"label":"[Inscription] Inauguration de l\u2019antenne Bande S \u2013 Observatoire du SIRTA","link":"https:\/\/academiespatiale.fr\/index.php\/event\/inscription-inauguration-de-lantenne-bande-s-observatoire-du-sirta\/"}],"_links":{"self":[{"href":"https:\/\/academiespatiale.fr\/index.php\/wp-json\/wp\/v2\/tribe_events\/8800","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/academiespatiale.fr\/index.php\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/academiespatiale.fr\/index.php\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/academiespatiale.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/academiespatiale.fr\/index.php\/wp-json\/wp\/v2\/tribe_events\/8800\/revisions"}],"predecessor-version":[{"id":8801,"href":"https:\/\/academiespatiale.fr\/index.php\/wp-json\/wp\/v2\/tribe_events\/8800\/revisions\/8801"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/academiespatiale.fr\/index.php\/wp-json\/wp\/v2\/media\/8790"}],"wp:attachment":[{"href":"https:\/\/academiespatiale.fr\/index.php\/wp-json\/wp\/v2\/media?parent=8800"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/academiespatiale.fr\/index.php\/wp-json\/wp\/v2\/tags?post=8800"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/academiespatiale.fr\/index.php\/wp-json\/wp\/v2\/tribe_events_cat?post=8800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}